{"id":11749,"date":"2022-10-05T18:04:53","date_gmt":"2022-10-05T23:04:53","guid":{"rendered":"https:\/\/contrastes.com.co\/digital\/?p=11749"},"modified":"2022-10-05T18:04:53","modified_gmt":"2022-10-05T23:04:53","slug":"identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad","status":"publish","type":"post","link":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/","title":{"rendered":"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad"},"content":{"rendered":"<p><strong>*Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad<\/strong><\/p>\n<blockquote><p><strong>Las v\u00edctimas fueron identificadas como Mart\u00edn Andr\u00e9s Polo Angulo, y F\u00e9lix Enrique Berrio. Ambos alcanzaron a ser trasladados a la Cl\u00ednica Los Almendros d\u00f3nde llegaron sin signos vitales.<\/strong><\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"alignleft  wp-image-8758\" src=\"https:\/\/contrastes.com.co\/digital\/wp-content\/uploads\/2022\/04\/d-capitular.png\" alt=\"\" width=\"62\" height=\"62\" \/>os personas resultaron muertas y dos m\u00e1s heridas luego de un ataque sicarial registrado la noche del martes en el <strong>polideportivo del barrio Los Almendros<\/strong> en el <strong>noroccidente del municipio de Soledad<\/strong>.<\/p>\n<p>Las v\u00edctimas fueron trasladadas a la <strong>Cl\u00ednica los Almendros<\/strong> cercana al lugar de los hechos, a la altura de la calle 83B con carrera 14, donde sujetos a bordo de una motocicleta llegaron al lugar y dispararon contra un grupo de personas que se encontraba reunidos.<\/p>\n<p>Las v\u00edctimas fueron identificadas como Mart\u00edn Andr\u00e9s Polo Angulo, y F\u00e9lix Enrique Berrio. Ambos alcanzaron a ser trasladados a la Cl\u00ednica Los Almendros d\u00f3nde llegaron sin signos vitales.<\/p>\n<p>Las otras dos personas que resultaron lesionadas no han sido identificadas. Al parecer, este nuevo hecho de sangre estar\u00eda relacionado con temas de microtr\u00e1fico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos personas resultaron muertas y dos m\u00e1s heridas luego de un ataque sicarial registrado la noche del martes en el polideportivo del barrio Los Almendros en el noroccidente del municipio de Soledad.<\/p>\n","protected":false},"author":1,"featured_media":11750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172,23],"tags":[7374,4866,5825,51,1037,7375,5108],"class_list":["post-11749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-judicial","category-locales","tag-clinica-los-almendros","tag-doble-homicidio","tag-heridos","tag-municipio-de-soledad","tag-noroccidente-de-soledad","tag-polideportivo-del-barrio-los-almendros","tag-sicariato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad - Constrastes<\/title>\n<meta name=\"description\" content=\"Dos personas resultaron muertas y dos m\u00e1s heridas luego de un ataque sicarial registrado la noche del martes en el polideportivo del barrio Los Almendros en el noroccidente del municipio de Soledad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad - Constrastes\" \/>\n<meta property=\"og:description\" content=\"Dos personas resultaron muertas y dos m\u00e1s heridas luego de un ataque sicarial registrado la noche del martes en el polideportivo del barrio Los Almendros en el noroccidente del municipio de Soledad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/\" \/>\n<meta property=\"og:site_name\" content=\"Constrastes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/guillo.pantoja.1\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-05T23:04:53+00:00\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\"},\"headline\":\"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad\",\"datePublished\":\"2022-10-05T23:04:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/\"},\"wordCount\":206,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Cl\u00ednica los Almendros\",\"doble homicidio\",\"heridos\",\"municipio de soledad\",\"noroccidente de Soledad\",\"polideportivo del barrio Los Almendros\",\"sicariato\"],\"articleSection\":[\"Judicial\",\"Locales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/\",\"name\":\"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad - Constrastes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-10-05T23:04:53+00:00\",\"description\":\"Dos personas resultaron muertas y dos m\u00e1s heridas luego de un ataque sicarial registrado la noche del martes en el polideportivo del barrio Los Almendros en el noroccidente del municipio de Soledad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2022\\\/10\\\/05\\\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"name\":\"Contrastes\",\"description\":\"Periodismo de Conciencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\",\"name\":\"Contrastes\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"contentUrl\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"width\":1536,\"height\":231,\"caption\":\"Contrastes\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/guillo.pantoja.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"sameAs\":[\"https:\\\/\\\/contrastes.com.co\\\/web\"],\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/author\\\/jdbobadilla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad - Constrastes","description":"Dos personas resultaron muertas y dos m\u00e1s heridas luego de un ataque sicarial registrado la noche del martes en el polideportivo del barrio Los Almendros en el noroccidente del municipio de Soledad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/","og_locale":"es_ES","og_type":"article","og_title":"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad - Constrastes","og_description":"Dos personas resultaron muertas y dos m\u00e1s heridas luego de un ataque sicarial registrado la noche del martes en el polideportivo del barrio Los Almendros en el noroccidente del municipio de Soledad.","og_url":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/","og_site_name":"Constrastes","article_publisher":"https:\/\/www.facebook.com\/guillo.pantoja.1","article_published_time":"2022-10-05T23:04:53+00:00","author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/#article","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/"},"author":{"name":"Editor","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02"},"headline":"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad","datePublished":"2022-10-05T23:04:53+00:00","mainEntityOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/"},"wordCount":206,"commentCount":0,"publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/#primaryimage"},"thumbnailUrl":"","keywords":["Cl\u00ednica los Almendros","doble homicidio","heridos","municipio de soledad","noroccidente de Soledad","polideportivo del barrio Los Almendros","sicariato"],"articleSection":["Judicial","Locales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/","url":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/","name":"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad - Constrastes","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/#primaryimage"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-10-05T23:04:53+00:00","description":"Dos personas resultaron muertas y dos m\u00e1s heridas luego de un ataque sicarial registrado la noche del martes en el polideportivo del barrio Los Almendros en el noroccidente del municipio de Soledad.","breadcrumb":{"@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/contrastes.com.co\/web\/2022\/10\/05\/identifican-a-los-dos-jovenes-asesinados-en-el-polideportivo-del-barrio-los-almendros-de-soledad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contrastes.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"Identifican a los dos j\u00f3venes asesinados en el polideportivo del barrio Los Almendros de Soledad"}]},{"@type":"WebSite","@id":"https:\/\/contrastes.com.co\/web\/#website","url":"https:\/\/contrastes.com.co\/web\/","name":"Contrastes","description":"Periodismo de Conciencia","publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contrastes.com.co\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contrastes.com.co\/web\/#organization","name":"Contrastes","url":"https:\/\/contrastes.com.co\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/","url":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","contentUrl":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","width":1536,"height":231,"caption":"Contrastes"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/guillo.pantoja.1"]},{"@type":"Person","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","caption":"Editor"},"sameAs":["https:\/\/contrastes.com.co\/web"],"url":"https:\/\/contrastes.com.co\/web\/author\/jdbobadilla\/"}]}},"blog_post_layout_featured_media_urls":{"thumbnail":"","full":""},"categories_names":{"172":{"name":"Judicial","link":"https:\/\/contrastes.com.co\/web\/category\/judicial\/"},"23":{"name":"Locales","link":"https:\/\/contrastes.com.co\/web\/category\/locales\/"}},"tags_names":{"7374":{"name":"Cl\u00ednica los Almendros","link":"https:\/\/contrastes.com.co\/web\/tag\/clinica-los-almendros\/"},"4866":{"name":"doble homicidio","link":"https:\/\/contrastes.com.co\/web\/tag\/doble-homicidio\/"},"5825":{"name":"heridos","link":"https:\/\/contrastes.com.co\/web\/tag\/heridos\/"},"51":{"name":"municipio de soledad","link":"https:\/\/contrastes.com.co\/web\/tag\/municipio-de-soledad\/"},"1037":{"name":"noroccidente de Soledad","link":"https:\/\/contrastes.com.co\/web\/tag\/noroccidente-de-soledad\/"},"7375":{"name":"polideportivo del barrio Los Almendros","link":"https:\/\/contrastes.com.co\/web\/tag\/polideportivo-del-barrio-los-almendros\/"},"5108":{"name":"sicariato","link":"https:\/\/contrastes.com.co\/web\/tag\/sicariato\/"}},"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":"","cvmm-medium":"","cvmm-medium-plus":"","cvmm-portrait":"","cvmm-medium-square":"","cvmm-large":"","cvmm-small":"","full":""},"_links":{"self":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/11749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/comments?post=11749"}],"version-history":[{"count":0,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/11749\/revisions"}],"wp:attachment":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/media?parent=11749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/categories?post=11749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/tags?post=11749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}