{"id":14085,"date":"2023-05-15T19:32:20","date_gmt":"2023-05-16T00:32:20","guid":{"rendered":"https:\/\/contrastes.com.co\/digital\/?p=14085"},"modified":"2023-05-15T19:32:20","modified_gmt":"2023-05-16T00:32:20","slug":"obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95","status":"publish","type":"post","link":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/","title":{"rendered":"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95%"},"content":{"rendered":"<p><strong>*Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95%<\/strong><\/p>\n<blockquote><p><strong>\u201cEn pr\u00f3ximos d\u00edas vamos a comenzar a inaugurar frentes de trabajo en Pumarejo, La Floresta y San Antonio, sectores que hist\u00f3ricamente nunca eran tenidos en cuenta para pavimentaci\u00f3n de sus calles, nuestra administraci\u00f3n decidi\u00f3 invertir y vemos muy contentos a los residentes\u201d: Rodolfo Ucr\u00f3s Rosales, alcalde de Soledad<\/strong><\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"alignleft  wp-image-8529\" src=\"https:\/\/contrastes.com.co\/digital\/wp-content\/uploads\/2022\/03\/e-capitular.png\" alt=\"e capitular\" width=\"72\" height=\"72\" \/>n los <strong>barrios Pumarejo, La Floresta y San Antonio<\/strong>, ubicados al <strong>suroriente de Soledad<\/strong>, las obras de pavimentaci\u00f3n vial, que adelanta la<strong> Alcald\u00eda de Soledad<\/strong>, avanzan en un 95%. Las nuevas v\u00edas <strong>benefician a m\u00e1s de 1.200 familias y contemplan la intervenci\u00f3n de 3.500 metro lineales de v\u00eda pavimentada, incluyendo la reposici\u00f3n de redes de alcantarillado y acueducto.<\/strong><\/p>\n<p>\u201cEn pr\u00f3ximos d\u00edas vamos a comenzar a inaugurar frentes de trabajo en Pumarejo, La Floresta y San Antonio, sectores que hist\u00f3ricamente nunca eran tenidos en cuenta para pavimentaci\u00f3n de sus calles, nuestra administraci\u00f3n decidi\u00f3 invertir y vemos muy contentos a los residentes\u201d, expres\u00f3 el alcalde Rodolfo Ucr\u00f3s Rosales, durante una visita de inspecci\u00f3n a las obras.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-14087 aligncenter\" src=\"https:\/\/contrastes.com.co\/digital\/wp-content\/uploads\/2023\/05\/rodovias23.jpg\" alt=\"rodo150523vias\" width=\"1080\" height=\"720\" \/><\/p>\n<p>Durante <strong>la administraci\u00f3n de Ucr\u00f3s Rosales se han entregado m\u00e1s 10 mil metros de v\u00edas pavimentadas<\/strong> en diferentes sectores del municipio.<\/p>\n<p>Continuamos avanzando en la ejecuci\u00f3n de programas de pavimentaci\u00f3n vial en: <strong>La Loma, 7 de Agosto, Centro, La Bonga, Pasito, Arboleda, Los Robles, Porvenir, Cruz de Mayo, Villa de las Moras, Los Arrayanes, Ferrocarril, Vista Hermosa, Villa Estadio, Las Moras, Villa M\u00f3naco, La Viola, Don Bosco IV, Los Cusules y La Esperanza<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los barrios Pumarejo, La Floresta y San Antonio, ubicados al suroriente de Soledad, las obras de pavimentaci\u00f3n vial, que adelanta la Alcald\u00eda de Soledad, avanzan en un 95%. Las nuevas v\u00edas benefician a m\u00e1s de 1.200 familias y contemplan la intervenci\u00f3n de 3.500 metro lineales de v\u00eda pavimentada, incluyendo la reposici\u00f3n de redes de alcantarillado y acueducto.<\/p>\n","protected":false},"author":1,"featured_media":14086,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,3542,1395],"tags":[173,9085,750,4945,9086,51,9087,1879],"class_list":["post-14085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","category-obras-publicas","category-vias-y-movilidad","tag-alcalde-de-soledad","tag-barrio-la-floresta","tag-barrio-pumarejo","tag-barrio-san-antonio","tag-barrios-del-suroriente-de-soledad","tag-municipio-de-soledad","tag-obras-de-pavimentacion-vial","tag-rodolfo-ucros-rosales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95% - Constrastes<\/title>\n<meta name=\"description\" content=\"En los barrios Pumarejo, La Floresta y San Antonio, ubicados al suroriente de Soledad, las obras de pavimentaci\u00f3n vial, que adelanta la Alcald\u00eda de Soledad, avanzan en un 95%. Las nuevas v\u00edas benefician a m\u00e1s de 1.200 familias y contemplan la intervenci\u00f3n de 3.500 metro lineales de v\u00eda pavimentada, incluyendo la reposici\u00f3n de redes de alcantarillado y acueducto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95% - Constrastes\" \/>\n<meta property=\"og:description\" content=\"En los barrios Pumarejo, La Floresta y San Antonio, ubicados al suroriente de Soledad, las obras de pavimentaci\u00f3n vial, que adelanta la Alcald\u00eda de Soledad, avanzan en un 95%. Las nuevas v\u00edas benefician a m\u00e1s de 1.200 familias y contemplan la intervenci\u00f3n de 3.500 metro lineales de v\u00eda pavimentada, incluyendo la reposici\u00f3n de redes de alcantarillado y acueducto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/\" \/>\n<meta property=\"og:site_name\" content=\"Constrastes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/guillo.pantoja.1\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-16T00:32:20+00:00\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\"},\"headline\":\"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95%\",\"datePublished\":\"2023-05-16T00:32:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/\"},\"wordCount\":287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"alcalde de Soledad\",\"barrio La Floresta\",\"Barrio Pumarejo.\",\"Barrio San Antonio\",\"barrios del suroriente de Soledad\",\"municipio de soledad\",\"Obras de pavimentaci\u00f3n vial\",\"Rodolfo Ucr\u00f3s Rosales\"],\"articleSection\":[\"Locales\",\"Obras P\u00fablicas\",\"V\u00edas y Movilidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/\",\"name\":\"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95% - Constrastes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-05-16T00:32:20+00:00\",\"description\":\"En los barrios Pumarejo, La Floresta y San Antonio, ubicados al suroriente de Soledad, las obras de pavimentaci\u00f3n vial, que adelanta la Alcald\u00eda de Soledad, avanzan en un 95%. Las nuevas v\u00edas benefician a m\u00e1s de 1.200 familias y contemplan la intervenci\u00f3n de 3.500 metro lineales de v\u00eda pavimentada, incluyendo la reposici\u00f3n de redes de alcantarillado y acueducto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/15\\\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"name\":\"Contrastes\",\"description\":\"Periodismo de Conciencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\",\"name\":\"Contrastes\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"contentUrl\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"width\":1536,\"height\":231,\"caption\":\"Contrastes\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/guillo.pantoja.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"sameAs\":[\"https:\\\/\\\/contrastes.com.co\\\/web\"],\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/author\\\/jdbobadilla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95% - Constrastes","description":"En los barrios Pumarejo, La Floresta y San Antonio, ubicados al suroriente de Soledad, las obras de pavimentaci\u00f3n vial, que adelanta la Alcald\u00eda de Soledad, avanzan en un 95%. Las nuevas v\u00edas benefician a m\u00e1s de 1.200 familias y contemplan la intervenci\u00f3n de 3.500 metro lineales de v\u00eda pavimentada, incluyendo la reposici\u00f3n de redes de alcantarillado y acueducto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/","og_locale":"es_ES","og_type":"article","og_title":"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95% - Constrastes","og_description":"En los barrios Pumarejo, La Floresta y San Antonio, ubicados al suroriente de Soledad, las obras de pavimentaci\u00f3n vial, que adelanta la Alcald\u00eda de Soledad, avanzan en un 95%. Las nuevas v\u00edas benefician a m\u00e1s de 1.200 familias y contemplan la intervenci\u00f3n de 3.500 metro lineales de v\u00eda pavimentada, incluyendo la reposici\u00f3n de redes de alcantarillado y acueducto.","og_url":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/","og_site_name":"Constrastes","article_publisher":"https:\/\/www.facebook.com\/guillo.pantoja.1","article_published_time":"2023-05-16T00:32:20+00:00","author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/#article","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/"},"author":{"name":"Editor","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02"},"headline":"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95%","datePublished":"2023-05-16T00:32:20+00:00","mainEntityOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/"},"wordCount":287,"commentCount":0,"publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/#primaryimage"},"thumbnailUrl":"","keywords":["alcalde de Soledad","barrio La Floresta","Barrio Pumarejo.","Barrio San Antonio","barrios del suroriente de Soledad","municipio de soledad","Obras de pavimentaci\u00f3n vial","Rodolfo Ucr\u00f3s Rosales"],"articleSection":["Locales","Obras P\u00fablicas","V\u00edas y Movilidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/","url":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/","name":"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95% - Constrastes","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/#primaryimage"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-05-16T00:32:20+00:00","description":"En los barrios Pumarejo, La Floresta y San Antonio, ubicados al suroriente de Soledad, las obras de pavimentaci\u00f3n vial, que adelanta la Alcald\u00eda de Soledad, avanzan en un 95%. Las nuevas v\u00edas benefician a m\u00e1s de 1.200 familias y contemplan la intervenci\u00f3n de 3.500 metro lineales de v\u00eda pavimentada, incluyendo la reposici\u00f3n de redes de alcantarillado y acueducto.","breadcrumb":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/15\/obras-de-pavimentacion-vial-en-tres-barrios-del-suroriente-de-soledad-avanzan-en-un-95\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contrastes.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"Obras de pavimentaci\u00f3n vial en tres barrios del suroriente de Soledad avanzan en un 95%"}]},{"@type":"WebSite","@id":"https:\/\/contrastes.com.co\/web\/#website","url":"https:\/\/contrastes.com.co\/web\/","name":"Contrastes","description":"Periodismo de Conciencia","publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contrastes.com.co\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contrastes.com.co\/web\/#organization","name":"Contrastes","url":"https:\/\/contrastes.com.co\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/","url":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","contentUrl":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","width":1536,"height":231,"caption":"Contrastes"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/guillo.pantoja.1"]},{"@type":"Person","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","caption":"Editor"},"sameAs":["https:\/\/contrastes.com.co\/web"],"url":"https:\/\/contrastes.com.co\/web\/author\/jdbobadilla\/"}]}},"blog_post_layout_featured_media_urls":{"thumbnail":"","full":""},"categories_names":{"23":{"name":"Locales","link":"https:\/\/contrastes.com.co\/web\/category\/locales\/"},"3542":{"name":"Obras P\u00fablicas","link":"https:\/\/contrastes.com.co\/web\/category\/obras-publicas\/"},"1395":{"name":"V\u00edas y Movilidad","link":"https:\/\/contrastes.com.co\/web\/category\/vias-y-movilidad\/"}},"tags_names":{"173":{"name":"alcalde de Soledad","link":"https:\/\/contrastes.com.co\/web\/tag\/alcalde-de-soledad\/"},"9085":{"name":"barrio La Floresta","link":"https:\/\/contrastes.com.co\/web\/tag\/barrio-la-floresta\/"},"750":{"name":"Barrio Pumarejo.","link":"https:\/\/contrastes.com.co\/web\/tag\/barrio-pumarejo\/"},"4945":{"name":"Barrio San Antonio","link":"https:\/\/contrastes.com.co\/web\/tag\/barrio-san-antonio\/"},"9086":{"name":"barrios del suroriente de Soledad","link":"https:\/\/contrastes.com.co\/web\/tag\/barrios-del-suroriente-de-soledad\/"},"51":{"name":"municipio de soledad","link":"https:\/\/contrastes.com.co\/web\/tag\/municipio-de-soledad\/"},"9087":{"name":"Obras de pavimentaci\u00f3n vial","link":"https:\/\/contrastes.com.co\/web\/tag\/obras-de-pavimentacion-vial\/"},"1879":{"name":"Rodolfo Ucr\u00f3s Rosales","link":"https:\/\/contrastes.com.co\/web\/tag\/rodolfo-ucros-rosales\/"}},"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":"","cvmm-medium":"","cvmm-medium-plus":"","cvmm-portrait":"","cvmm-medium-square":"","cvmm-large":"","cvmm-small":"","full":""},"_links":{"self":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/14085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/comments?post=14085"}],"version-history":[{"count":0,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/14085\/revisions"}],"wp:attachment":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/media?parent=14085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/categories?post=14085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/tags?post=14085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}