{"id":14120,"date":"2023-05-22T12:49:44","date_gmt":"2023-05-22T17:49:44","guid":{"rendered":"https:\/\/contrastes.com.co\/digital\/?p=14120"},"modified":"2023-05-22T12:49:44","modified_gmt":"2023-05-22T17:49:44","slug":"sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento","status":"publish","type":"post","link":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/","title":{"rendered":"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento"},"content":{"rendered":"<p><strong>*Sector Salud de Soledad firm\u00f3 apoy\u00f2 a nuestro movimiento<\/strong><\/p>\n<blockquote><p><strong>M\u00e9dicos, enfermeras, auxiliares de enfermer\u00eda, tecn\u00f3logos y t\u00e9cnicos del \u00e1rea de la salud del municipio de Soledad, realizaron una jornada especial de recolecci\u00f3n de firmas para apoyar la intenci\u00f3n del Grupo Significativo de Ciudadanos Estamos con Alcira de llevar como candidata para la Alcald\u00eda a la M\u00e9dico Alcira Sandoval Ib\u00e1\u00f1ez.<\/strong><\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"alignleft  wp-image-8927\" src=\"https:\/\/contrastes.com.co\/digital\/wp-content\/uploads\/2022\/04\/comillas-capitular-2.png\" alt=\"comillas capitular 2\" width=\"60\" height=\"60\" \/>Estoy muy agradecida y emocionada por recibir este afectuoso saludo de excompa\u00f1eros de trabajo, colegas y personal del sector salud con quienes he trabajado por la causa que nos une: sanar a quienes buscan en nosotros esa posibilidad, por eso hoy agradezco infinitamente su apoyo con tantas firmas de respaldo a mi proyecto democr\u00e1tico, firmas que sellan este compromiso mutuo para sanar a nuestra ciudad de la indolencia, la inseguridad, la falta de oportunidades, el desempleo y otras tantas circunstancias que hoy nos causan dolor social\u201d, dijo la considerada M\u00e9dico del pueblo durante su intervenci\u00f3n en el <strong>Encuentro de Amigos del Sector Salud<\/strong>, desarrollado en el municipio de Soledad, al que ella asisti\u00f3 en calidad de homenajeada por sus excompa\u00f1eros de trabajo.<\/p>\n<figure id=\"attachment_14123\" aria-describedby=\"caption-attachment-14123\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-14123 size-full\" src=\"https:\/\/contrastes.com.co\/digital\/wp-content\/uploads\/2023\/05\/saludalcira3.jpg\" alt=\"saludalcira3\" width=\"1200\" height=\"698\" \/><figcaption id=\"caption-attachment-14123\" class=\"wp-caption-text\">En la sede de Combarranquilla en Soledad se contabilizaron 1.780 firmas de respaldo a la causa del Grupo Significativo de Ciudadanos Estamos con Alcira.<\/figcaption><\/figure>\n<p>En el mismo m\u00e9dicos, enfermeras, auxiliares de enfermer\u00eda, tecn\u00f3logos y t\u00e9cnicos del \u00e1rea de la salud del municipio de Soledad, realizaron una jornada especial de recolecci\u00f3n de firmas para apoyar la intenci\u00f3n del <strong>Grupo Significativo de Ciudadanos Estamos con Alcira de llevar como candidata para la Alcald\u00eda a la M\u00e9dico Alcira Sandoval Ib\u00e1\u00f1ez.<\/strong> Durante el evento, cumplido en la sede de <strong>Combarranquilla en Soledad<\/strong> se contabilizaron 1.780 firmas de respaldo a la causa de nuestro Grupo Significativo de Ciudadanos Estamos con Alcira.<\/p>\n<h3>Alfredo Varela, precandidato a la Gobernaci\u00f3n destaca proceso de GSC Estamos con Alcira<\/h3>\n<figure id=\"attachment_14122\" aria-describedby=\"caption-attachment-14122\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-14122 size-full\" src=\"https:\/\/contrastes.com.co\/digital\/wp-content\/uploads\/2023\/05\/alciravarela.jpg\" alt=\"alciravarela23\" width=\"1200\" height=\"783\" \/><figcaption id=\"caption-attachment-14122\" class=\"wp-caption-text\">El joven empresario y l\u00edder pol\u00edtico, Alfredo Varela, quien aspira al primer cargo departamental, coincidi\u00f3 con la M\u00e9dico Alcira Sandoval durante el Encuentro de Amigos del Sector Salud, organizado por los profesionales de esa \u00e1rea<\/figcaption><\/figure>\n<p>\u201cAlcira es una voz valiosa, preparada y comprometida de las familias de Soledad que quieren que este municipio se desarrolle en todos sus aspectos y augur\u00f3 que este bonito proceso de recolecci\u00f3n de firmas que est\u00e1 adelantando sea exitoso y la puedan no s\u00f3lo inscribir como candidata a la Alcald\u00eda, sino que gane el debate para el bienestar de la ciudad\u201d dijo el <strong>precandidato a la Gobernaci\u00f3n del Atl\u00e1ntico Alfredo Varela.<\/strong><\/p>\n<figure id=\"attachment_14124\" aria-describedby=\"caption-attachment-14124\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14124 size-full\" src=\"https:\/\/contrastes.com.co\/digital\/wp-content\/uploads\/2023\/05\/alcirasalud4.jpg\" alt=\"alcirasalud4\" width=\"1200\" height=\"604\" \/><figcaption id=\"caption-attachment-14124\" class=\"wp-caption-text\">As\u00ed luc\u00eda la sede de Combarranquilla en Soledad, donde integrantes del sector salud respaldaron con su firma la opci\u00f3n propuesta por el Grupo Significativo de Ciudadanos Estamos con Alcira.<\/figcaption><\/figure>\n<p>El joven empresario y l\u00edder pol\u00edtico, quien aspira al primer cargo departamental, coincidi\u00f3 con la M\u00e9dico Alcira Sandoval durante el <strong>Encuentro de Amigos del Sector Salud<\/strong>, organizado por los profesionales de esa \u00e1rea, quienes expusieron temas relacionados con la necesidad de trabajo intersectorial que brinde oportunidad, calidad, eficiencia, humanismo y efectividad en la prestaci\u00f3n de los servicios de salud para los solede\u00f1os, temas en los que se encuentran comprometidos los profesionales del municipio de Soledad que apoyan a su colega <strong>Alcira Sandoval Ib\u00e1\u00f1ez<\/strong>.<\/p>\n<figure id=\"attachment_14125\" aria-describedby=\"caption-attachment-14125\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14125 size-full\" src=\"https:\/\/contrastes.com.co\/digital\/wp-content\/uploads\/2023\/05\/saludalcira2.jpg\" alt=\"saludalcira2\" width=\"1200\" height=\"637\" \/><figcaption id=\"caption-attachment-14125\" class=\"wp-caption-text\">M\u00e9dicos, enfermeras, auxiliares de enfermer\u00eda, tecn\u00f3logos y t\u00e9cnicos del \u00e1rea de la salud del municipio de Soledad, realizaron una jornada especial de recolecci\u00f3n de firmas para apoyar la intenci\u00f3n del Grupo Significativo de Ciudadanos Estamos con Alcira de llevar como candidata para la Alcald\u00eda a la M\u00e9dico Alcira Sandoval Ib\u00e1\u00f1ez.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00abEstoy muy agradecida y emocionada por recibir este afectuoso saludo de excompa\u00f1eros de trabajo, colegas y personal del sector salud con quienes he trabajado por la causa que nos une: sanar a quienes buscan en nosotros esa posibilidad, por eso hoy agradezco infinitamente su apoyo con tantas firmas de respaldo a mi proyecto democr\u00e1tico, firmas que sellan este compromiso mutuo para sanar a nuestra ciudad de la indolencia, la inseguridad, la falta de oportunidades, el desempleo y otras tantas circunstancias que hoy nos causan dolor social\u201d, dijo la considerada M\u00e9dico del pueblo durante su intervenci\u00f3n en el Encuentro de Amigos del Sector Salud, desarrollado en el municipio de Soledad, al que ella asisti\u00f3 en calidad de homenajeada por sus excompa\u00f1eros de trabajo.<\/p>\n","protected":false},"author":1,"featured_media":14121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8453,23,25],"tags":[30,9104,9105,8314,9106,51,9107],"class_list":["post-14120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad","category-elecciones-regionales-2023","category-locales","category-salud","tag-alcira-sandoval-ibanez","tag-alfredo-varela","tag-encuentro-de-amigos-del-sector-salud","tag-grupo-significativo-de-ciudadanos-estamos-con-alcira","tag-medico-alcira-sandoval-ibanez","tag-municipio-de-soledad","tag-precandidato-a-la-gobernacion-del-atlantico-alfredo-varela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento - Constrastes<\/title>\n<meta name=\"description\" content=\"&quot;Estoy muy agradecida y emocionada por recibir este afectuoso saludo de excompa\u00f1eros de trabajo, colegas y personal del sector salud con quienes he trabajado por la causa que nos une: sanar a quienes buscan en nosotros esa posibilidad, por eso hoy agradezco infinitamente su apoyo con tantas firmas de respaldo a mi proyecto democr\u00e1tico, firmas que sellan este compromiso mutuo para sanar a nuestra ciudad de la indolencia, la inseguridad, la falta de oportunidades, el desempleo y otras tantas circunstancias que hoy nos causan dolor social\u201d, dijo la considerada M\u00e9dico del pueblo durante su intervenci\u00f3n en el Encuentro de Amigos del Sector Salud, desarrollado en el municipio de Soledad, al que ella asisti\u00f3 en calidad de homenajeada por sus excompa\u00f1eros de trabajo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento - Constrastes\" \/>\n<meta property=\"og:description\" content=\"&quot;Estoy muy agradecida y emocionada por recibir este afectuoso saludo de excompa\u00f1eros de trabajo, colegas y personal del sector salud con quienes he trabajado por la causa que nos une: sanar a quienes buscan en nosotros esa posibilidad, por eso hoy agradezco infinitamente su apoyo con tantas firmas de respaldo a mi proyecto democr\u00e1tico, firmas que sellan este compromiso mutuo para sanar a nuestra ciudad de la indolencia, la inseguridad, la falta de oportunidades, el desempleo y otras tantas circunstancias que hoy nos causan dolor social\u201d, dijo la considerada M\u00e9dico del pueblo durante su intervenci\u00f3n en el Encuentro de Amigos del Sector Salud, desarrollado en el municipio de Soledad, al que ella asisti\u00f3 en calidad de homenajeada por sus excompa\u00f1eros de trabajo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Constrastes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/guillo.pantoja.1\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-22T17:49:44+00:00\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\"},\"headline\":\"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento\",\"datePublished\":\"2023-05-22T17:49:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/\"},\"wordCount\":652,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Alcira Sandoval Ib\u00e1\u00f1ez\",\"Alfredo Varela\",\"Encuentro de Amigos del Sector Salud\",\"grupo significativo de ciudadanos \\\"Estamos con Alcira\\\"\",\"M\u00e9dico Alcira Sandoval Ib\u00e1\u00f1ez\",\"municipio de soledad\",\"precandidato a la Gobernaci\u00f3n del Atl\u00e1ntico Alfredo Varela\"],\"articleSection\":[\"Comunidad\",\"Elecciones Regionales 2023\",\"Locales\",\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/\",\"name\":\"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento - Constrastes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-05-22T17:49:44+00:00\",\"description\":\"\\\"Estoy muy agradecida y emocionada por recibir este afectuoso saludo de excompa\u00f1eros de trabajo, colegas y personal del sector salud con quienes he trabajado por la causa que nos une: sanar a quienes buscan en nosotros esa posibilidad, por eso hoy agradezco infinitamente su apoyo con tantas firmas de respaldo a mi proyecto democr\u00e1tico, firmas que sellan este compromiso mutuo para sanar a nuestra ciudad de la indolencia, la inseguridad, la falta de oportunidades, el desempleo y otras tantas circunstancias que hoy nos causan dolor social\u201d, dijo la considerada M\u00e9dico del pueblo durante su intervenci\u00f3n en el Encuentro de Amigos del Sector Salud, desarrollado en el municipio de Soledad, al que ella asisti\u00f3 en calidad de homenajeada por sus excompa\u00f1eros de trabajo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2023\\\/05\\\/22\\\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"name\":\"Contrastes\",\"description\":\"Periodismo de Conciencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\",\"name\":\"Contrastes\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"contentUrl\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"width\":1536,\"height\":231,\"caption\":\"Contrastes\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/guillo.pantoja.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"sameAs\":[\"https:\\\/\\\/contrastes.com.co\\\/web\"],\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/author\\\/jdbobadilla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento - Constrastes","description":"\"Estoy muy agradecida y emocionada por recibir este afectuoso saludo de excompa\u00f1eros de trabajo, colegas y personal del sector salud con quienes he trabajado por la causa que nos une: sanar a quienes buscan en nosotros esa posibilidad, por eso hoy agradezco infinitamente su apoyo con tantas firmas de respaldo a mi proyecto democr\u00e1tico, firmas que sellan este compromiso mutuo para sanar a nuestra ciudad de la indolencia, la inseguridad, la falta de oportunidades, el desempleo y otras tantas circunstancias que hoy nos causan dolor social\u201d, dijo la considerada M\u00e9dico del pueblo durante su intervenci\u00f3n en el Encuentro de Amigos del Sector Salud, desarrollado en el municipio de Soledad, al que ella asisti\u00f3 en calidad de homenajeada por sus excompa\u00f1eros de trabajo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento - Constrastes","og_description":"\"Estoy muy agradecida y emocionada por recibir este afectuoso saludo de excompa\u00f1eros de trabajo, colegas y personal del sector salud con quienes he trabajado por la causa que nos une: sanar a quienes buscan en nosotros esa posibilidad, por eso hoy agradezco infinitamente su apoyo con tantas firmas de respaldo a mi proyecto democr\u00e1tico, firmas que sellan este compromiso mutuo para sanar a nuestra ciudad de la indolencia, la inseguridad, la falta de oportunidades, el desempleo y otras tantas circunstancias que hoy nos causan dolor social\u201d, dijo la considerada M\u00e9dico del pueblo durante su intervenci\u00f3n en el Encuentro de Amigos del Sector Salud, desarrollado en el municipio de Soledad, al que ella asisti\u00f3 en calidad de homenajeada por sus excompa\u00f1eros de trabajo.","og_url":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/","og_site_name":"Constrastes","article_publisher":"https:\/\/www.facebook.com\/guillo.pantoja.1","article_published_time":"2023-05-22T17:49:44+00:00","author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/#article","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/"},"author":{"name":"Editor","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02"},"headline":"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento","datePublished":"2023-05-22T17:49:44+00:00","mainEntityOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/"},"wordCount":652,"commentCount":0,"publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/#primaryimage"},"thumbnailUrl":"","keywords":["Alcira Sandoval Ib\u00e1\u00f1ez","Alfredo Varela","Encuentro de Amigos del Sector Salud","grupo significativo de ciudadanos \"Estamos con Alcira\"","M\u00e9dico Alcira Sandoval Ib\u00e1\u00f1ez","municipio de soledad","precandidato a la Gobernaci\u00f3n del Atl\u00e1ntico Alfredo Varela"],"articleSection":["Comunidad","Elecciones Regionales 2023","Locales","Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/","url":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/","name":"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento - Constrastes","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/#primaryimage"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-05-22T17:49:44+00:00","description":"\"Estoy muy agradecida y emocionada por recibir este afectuoso saludo de excompa\u00f1eros de trabajo, colegas y personal del sector salud con quienes he trabajado por la causa que nos une: sanar a quienes buscan en nosotros esa posibilidad, por eso hoy agradezco infinitamente su apoyo con tantas firmas de respaldo a mi proyecto democr\u00e1tico, firmas que sellan este compromiso mutuo para sanar a nuestra ciudad de la indolencia, la inseguridad, la falta de oportunidades, el desempleo y otras tantas circunstancias que hoy nos causan dolor social\u201d, dijo la considerada M\u00e9dico del pueblo durante su intervenci\u00f3n en el Encuentro de Amigos del Sector Salud, desarrollado en el municipio de Soledad, al que ella asisti\u00f3 en calidad de homenajeada por sus excompa\u00f1eros de trabajo.","breadcrumb":{"@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/contrastes.com.co\/web\/2023\/05\/22\/sector-salud-de-soledad-firmo-apoyo-a-nuestro-movimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contrastes.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"Sector Salud de Soledad firm\u00f3 apoy\u00f3 a nuestro movimiento"}]},{"@type":"WebSite","@id":"https:\/\/contrastes.com.co\/web\/#website","url":"https:\/\/contrastes.com.co\/web\/","name":"Contrastes","description":"Periodismo de Conciencia","publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contrastes.com.co\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contrastes.com.co\/web\/#organization","name":"Contrastes","url":"https:\/\/contrastes.com.co\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/","url":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","contentUrl":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","width":1536,"height":231,"caption":"Contrastes"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/guillo.pantoja.1"]},{"@type":"Person","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","caption":"Editor"},"sameAs":["https:\/\/contrastes.com.co\/web"],"url":"https:\/\/contrastes.com.co\/web\/author\/jdbobadilla\/"}]}},"blog_post_layout_featured_media_urls":{"thumbnail":"","full":""},"categories_names":{"10":{"name":"Comunidad","link":"https:\/\/contrastes.com.co\/web\/category\/comunidad\/"},"8453":{"name":"Elecciones Regionales 2023","link":"https:\/\/contrastes.com.co\/web\/category\/elecciones-regionales-2023\/"},"23":{"name":"Locales","link":"https:\/\/contrastes.com.co\/web\/category\/locales\/"},"25":{"name":"Salud","link":"https:\/\/contrastes.com.co\/web\/category\/salud\/"}},"tags_names":{"30":{"name":"Alcira Sandoval Ib\u00e1\u00f1ez","link":"https:\/\/contrastes.com.co\/web\/tag\/alcira-sandoval-ibanez\/"},"9104":{"name":"Alfredo Varela","link":"https:\/\/contrastes.com.co\/web\/tag\/alfredo-varela\/"},"9105":{"name":"Encuentro de Amigos del Sector Salud","link":"https:\/\/contrastes.com.co\/web\/tag\/encuentro-de-amigos-del-sector-salud\/"},"8314":{"name":"grupo significativo de ciudadanos \"Estamos con Alcira\"","link":"https:\/\/contrastes.com.co\/web\/tag\/grupo-significativo-de-ciudadanos-estamos-con-alcira\/"},"9106":{"name":"M\u00e9dico Alcira Sandoval Ib\u00e1\u00f1ez","link":"https:\/\/contrastes.com.co\/web\/tag\/medico-alcira-sandoval-ibanez\/"},"51":{"name":"municipio de soledad","link":"https:\/\/contrastes.com.co\/web\/tag\/municipio-de-soledad\/"},"9107":{"name":"precandidato a la Gobernaci\u00f3n del Atl\u00e1ntico Alfredo Varela","link":"https:\/\/contrastes.com.co\/web\/tag\/precandidato-a-la-gobernacion-del-atlantico-alfredo-varela\/"}},"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":"","cvmm-medium":"","cvmm-medium-plus":"","cvmm-portrait":"","cvmm-medium-square":"","cvmm-large":"","cvmm-small":"","full":""},"_links":{"self":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/14120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/comments?post=14120"}],"version-history":[{"count":0,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/14120\/revisions"}],"wp:attachment":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/media?parent=14120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/categories?post=14120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/tags?post=14120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}