{"id":15453,"date":"2024-11-21T23:38:29","date_gmt":"2024-11-22T04:38:29","guid":{"rendered":"https:\/\/contrastes.com.co\/digital\/?p=15453"},"modified":"2024-11-21T23:38:29","modified_gmt":"2024-11-22T04:38:29","slug":"junior-gana-primer-juego-del-cuadrangular","status":"publish","type":"post","link":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/","title":{"rendered":"Junior Gana Primer Juego Del Cuadrangular"},"content":{"rendered":"<blockquote><p><em><strong>En un mal juego del equipo tibur\u00f3n, America De Cali encerr\u00f3 a junior durante casi todo el partido a tal punto de hacer figura al arquero Jeferson Martinez.<\/strong><\/em><\/p><\/blockquote>\n<p>Noviembre 22 &#8211; 2024<\/p>\n<p>&nbsp;<\/p>\n<p>Por : Lester Padilla Sanchez.<\/p>\n<p>&nbsp;<\/p>\n<p>Junior obtuvo su primera victoria en el estadio Metropolitano en la primera fecha de los cuadrangulares finales del torneo finalizaci\u00f3n 2024, con anotaci\u00f3n de Carlos Baca a los 18 minutos del primer tiempo.<\/p>\n<p>Aunque la victoria es siempre gratificante por tratarse de las finales, qued\u00f3 en el ambiente la premisa que el equipo no jugo su mejor partido, nunca tuvo la oportunidad de sostener el bal\u00f3n y tuvo que resistir los ataques rivales. Junior se vio sometido y sin soluciones para quitarse el asedio rival.<\/p>\n<p>El planteamiento inicial sorprendi\u00f3 el t\u00e9cnico varias con tres volantes de primera linea como lo son Cantillo, Moreno y V\u00e9lez, dos volantes armadores como Enamorado y Chara dejando en punta. a Baca. Con todo y Junior obtuvo el gol tras jugada de centro de Moreno para que Baca anote. Despu\u00e9s de esto, el America someti\u00f3 literalmente a junior con 9 llegadas tres de ellas siendo salvadas de Jeferson Martinez.<\/p>\n<p>El segundo tiempo ingresa Yairo Moreno por Velez y se pensaba que con un volante mas para la creaci\u00f3n ser\u00eda distinto, esto solo funciono en la primera jugada en donde Didier Moreno remata al arco y la pelota pega en un pie de un defensor americano para ahogar el grito de gol, de ahi en adelante el equipo visitante someti\u00f3 a Junior nuevamente.<\/p>\n<p>America de Cali logro toda la posesi\u00f3n del segundo tiempo generando 8 opciones de gol de las cuales 4 de ellas fueron salvadas providencialmente por el arquero Martinez. Farias ingresa un volante de marca mas para regresar a ese 3 defensivo pero eso no impidi\u00f3 que se viera superior en el juego.<\/p>\n<p>Se destaca la victoria, ya que siempre ser\u00e1 importante iniciar ganando, El regreso de Carlos Baca al gol, pero Junior debe mostrar un mejor juego y no depender de la suerte, la imprecisi\u00f3n del equipo rival y la buena actuaci\u00f3n de nuestro arquero. Hay que mejorar, ya que en este partido no se pudo mostrar un juego fluido y seguro.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>&nbsp;<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>En un mal juego del equipo tibur\u00f3n, America De Cali encerr\u00f3 a junior durante casi todo el partido a tal punto de hacer figura al arquero Jeferson Martinez. Noviembre 22 &#8211; 2024 &nbsp; Por : Lester Padilla Sanchez. &nbsp; Junior obtuvo su primera victoria en el estadio Metropolitano en la primera fecha de los cuadrangulares [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8566,151,9620,8562,23,101,3348,4940],"tags":[],"class_list":["post-15453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colombia-hoy","category-deportes","category-junior-de-barranquilla","category-lester-padilla","category-locales","category-pais","category-television","category-television-web"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Junior Gana Primer Juego Del Cuadrangular - Constrastes<\/title>\n<meta name=\"description\" content=\"Junior obtuvo su primera victoria en el estadio Metropolitano en la primera fecha de los cuadrangulares finales del torneo finalizaci\u00f3n 2024, con anotaci\u00f3n de Carlos Baca a los 18 minutos del primer tiempo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Junior Gana Primer Juego Del Cuadrangular - Constrastes\" \/>\n<meta property=\"og:description\" content=\"Junior obtuvo su primera victoria en el estadio Metropolitano en la primera fecha de los cuadrangulares finales del torneo finalizaci\u00f3n 2024, con anotaci\u00f3n de Carlos Baca a los 18 minutos del primer tiempo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/\" \/>\n<meta property=\"og:site_name\" content=\"Constrastes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/guillo.pantoja.1\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-22T04:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\"},\"headline\":\"Junior Gana Primer Juego Del Cuadrangular\",\"datePublished\":\"2024-11-22T04:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/\"},\"wordCount\":379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/La-Sintesis-Junior-3-x-America-1-1.jpg\",\"articleSection\":[\"Colombia Hoy\",\"Deportes\",\"Junior de Barranquilla\",\"Lester Padilla\",\"Locales\",\"Pa\u00eds\",\"Televisi\u00f3n\",\"Televisi\u00f3n-Web\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/\",\"name\":\"Junior Gana Primer Juego Del Cuadrangular - Constrastes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/La-Sintesis-Junior-3-x-America-1-1.jpg\",\"datePublished\":\"2024-11-22T04:38:29+00:00\",\"description\":\"Junior obtuvo su primera victoria en el estadio Metropolitano en la primera fecha de los cuadrangulares finales del torneo finalizaci\u00f3n 2024, con anotaci\u00f3n de Carlos Baca a los 18 minutos del primer tiempo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/#primaryimage\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/La-Sintesis-Junior-3-x-America-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/La-Sintesis-Junior-3-x-America-1-1.jpg\",\"width\":700,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2024\\\/11\\\/21\\\/junior-gana-primer-juego-del-cuadrangular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Junior Gana Primer Juego Del Cuadrangular\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"name\":\"Contrastes\",\"description\":\"Periodismo de Conciencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\",\"name\":\"Contrastes\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"contentUrl\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"width\":1536,\"height\":231,\"caption\":\"Contrastes\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/guillo.pantoja.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"sameAs\":[\"https:\\\/\\\/contrastes.com.co\\\/web\"],\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/author\\\/jdbobadilla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Junior Gana Primer Juego Del Cuadrangular - Constrastes","description":"Junior obtuvo su primera victoria en el estadio Metropolitano en la primera fecha de los cuadrangulares finales del torneo finalizaci\u00f3n 2024, con anotaci\u00f3n de Carlos Baca a los 18 minutos del primer tiempo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/","og_locale":"es_ES","og_type":"article","og_title":"Junior Gana Primer Juego Del Cuadrangular - Constrastes","og_description":"Junior obtuvo su primera victoria en el estadio Metropolitano en la primera fecha de los cuadrangulares finales del torneo finalizaci\u00f3n 2024, con anotaci\u00f3n de Carlos Baca a los 18 minutos del primer tiempo.","og_url":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/","og_site_name":"Constrastes","article_publisher":"https:\/\/www.facebook.com\/guillo.pantoja.1","article_published_time":"2024-11-22T04:38:29+00:00","og_image":[{"width":700,"height":500,"url":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/#article","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/"},"author":{"name":"Editor","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02"},"headline":"Junior Gana Primer Juego Del Cuadrangular","datePublished":"2024-11-22T04:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/"},"wordCount":379,"commentCount":0,"publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/#primaryimage"},"thumbnailUrl":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg","articleSection":["Colombia Hoy","Deportes","Junior de Barranquilla","Lester Padilla","Locales","Pa\u00eds","Televisi\u00f3n","Televisi\u00f3n-Web"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/","url":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/","name":"Junior Gana Primer Juego Del Cuadrangular - Constrastes","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/#primaryimage"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/#primaryimage"},"thumbnailUrl":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg","datePublished":"2024-11-22T04:38:29+00:00","description":"Junior obtuvo su primera victoria en el estadio Metropolitano en la primera fecha de los cuadrangulares finales del torneo finalizaci\u00f3n 2024, con anotaci\u00f3n de Carlos Baca a los 18 minutos del primer tiempo.","breadcrumb":{"@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/#primaryimage","url":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg","contentUrl":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg","width":700,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/contrastes.com.co\/web\/2024\/11\/21\/junior-gana-primer-juego-del-cuadrangular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contrastes.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"Junior Gana Primer Juego Del Cuadrangular"}]},{"@type":"WebSite","@id":"https:\/\/contrastes.com.co\/web\/#website","url":"https:\/\/contrastes.com.co\/web\/","name":"Contrastes","description":"Periodismo de Conciencia","publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contrastes.com.co\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contrastes.com.co\/web\/#organization","name":"Contrastes","url":"https:\/\/contrastes.com.co\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/","url":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","contentUrl":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","width":1536,"height":231,"caption":"Contrastes"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/guillo.pantoja.1"]},{"@type":"Person","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","caption":"Editor"},"sameAs":["https:\/\/contrastes.com.co\/web"],"url":"https:\/\/contrastes.com.co\/web\/author\/jdbobadilla\/"}]}},"blog_post_layout_featured_media_urls":{"thumbnail":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1-150x150.jpg",150,150,true],"full":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg",700,500,false]},"categories_names":{"8566":{"name":"Colombia Hoy","link":"https:\/\/contrastes.com.co\/web\/category\/colombia-hoy\/"},"151":{"name":"Deportes","link":"https:\/\/contrastes.com.co\/web\/category\/deportes\/"},"9620":{"name":"Junior de Barranquilla","link":"https:\/\/contrastes.com.co\/web\/category\/junior-de-barranquilla\/"},"8562":{"name":"Lester Padilla","link":"https:\/\/contrastes.com.co\/web\/category\/lester-padilla\/"},"23":{"name":"Locales","link":"https:\/\/contrastes.com.co\/web\/category\/locales\/"},"101":{"name":"Pa\u00eds","link":"https:\/\/contrastes.com.co\/web\/category\/pais\/"},"3348":{"name":"Televisi\u00f3n","link":"https:\/\/contrastes.com.co\/web\/category\/television\/"},"4940":{"name":"Televisi\u00f3n-Web","link":"https:\/\/contrastes.com.co\/web\/category\/television-web\/"}},"tags_names":[],"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1-150x150.jpg",150,150,true],"cvmm-medium":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg",300,214,false],"cvmm-medium-plus":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg",290,207,false],"cvmm-portrait":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg",400,286,false],"cvmm-medium-square":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg",600,429,false],"cvmm-large":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg",700,500,false],"cvmm-small":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg",130,93,false],"full":["https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2024\/11\/La-Sintesis-Junior-3-x-America-1-1.jpg",700,500,false]},"_links":{"self":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/15453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/comments?post=15453"}],"version-history":[{"count":0,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/15453\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/media\/15455"}],"wp:attachment":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/media?parent=15453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/categories?post=15453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/tags?post=15453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}