{"id":6365,"date":"2021-06-16T17:13:59","date_gmt":"2021-06-16T22:13:59","guid":{"rendered":"https:\/\/contrastes.com.co\/digital\/?p=6365"},"modified":"2021-06-16T17:13:59","modified_gmt":"2021-06-16T22:13:59","slug":"vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares","status":"publish","type":"post","link":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/","title":{"rendered":"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares"},"content":{"rendered":"<p><strong>\u201cCon el subsidio adicional del departamento, lograremos que 5 mil familias tengan vivienda propia\u201d: Elsa Noguera<\/strong><\/p>\n<blockquote><p><strong>*La Gobernadora del Atl\u00e1ntico present\u00f3 el nuevo subsidio departamental, adicional al nacional \u2018Mi Casa Ya\u2019, que busca que familias con ingresos de hasta 2 salarios m\u00ednimos puedan acceder a una Vivienda de Inter\u00e9s Prioritario (VIP) en 21 municipios del departamento (excepto Soledad y Barranquilla).<\/strong><\/p>\n<p><strong>*La meta de la administraci\u00f3n departamental es lograr otorgar 1.600 subsidios durante este a\u00f1o y un total de 5 mil para el a\u00f1o 2023.<\/strong><\/p>\n<p><strong>*La inversi\u00f3n destinada por la Gobernaci\u00f3n del Atl\u00e1ntico para el programa \u2018Vivienda para la Gente\u2019 es de 31 mil millones de pesos.<\/strong><\/p><\/blockquote>\n<p><strong>Barranquilla.-<\/strong> Con el prop\u00f3sito de que m\u00e1s familias atlanticenses cumplan el sue\u00f1o de tener casa propia, la <strong>gobernadora del Atl\u00e1ntico, Elsa Noguera<\/strong>, <strong>present\u00f3 el subsidio adicional departamental \u2018Vivienda para la Gente\u2019<\/strong>, que beneficiar\u00e1 a 5 mil hogares y se suma al que entrega el Gobierno Nacional \u2018<strong>Mi Casa Ya<\/strong>\u2019.<\/p>\n<p>Durante el lanzamiento de este programa, la mandataria departamental explic\u00f3 que el subsidio adicional busca que las personas de bajos ingresos puedan acceder a una <strong>Vivienda de Inter\u00e9s Prioritario (VIP)<\/strong> que correspondan a proyectos ubicados en 21 municipios del departamento (excepto Soledad y Barranquilla).<\/p>\n<p>\u201cHoy con mucho orgullo queremos anunciar que el Atl\u00e1ntico es el primer departamento que asigna un subsidio complementario, con el mismo esquema del programa nacional \u2018Mi Casa Ya\u2019. <strong>Las familias que tengan ingresos hasta de 1 mill\u00f3n 800 mil pesos, y que quieran adquirir una vivienda de hasta 81 millones de pesos, podr\u00e1n tener un subsidio de 6 millones 400 mil pesos m\u00e1s,<\/strong> para cerrar la compra de su vivienda\u201d, explic\u00f3 la mandataria, quien agreg\u00f3 que el objetivo es que la cuota del banco que pague el beneficiario sea menor (cerca de 280 mil pesos) a lo que hoy paga en arriendo.<\/p>\n<p><iframe style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fwww.facebook.com%2Fsoycontrastes%2Fvideos%2F332747398226611%2F&amp;show_text=false&amp;width=560&amp;t=0\" width=\"720\" height=\"404\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>De igual forma, la Gobernadora agreg\u00f3 que la construcci\u00f3n de vivienda es un gran dinamizador de la econom\u00eda, pero sobre todo contribuye a transformar vidas. \u201cEl compromiso es que, si logramos colocar estos subsidios r\u00e1pidamente, con seguridad destinaremos m\u00e1s recursos desde la administraci\u00f3n departamental. <strong>Nuestra meta para este a\u00f1o es otorgar por lo menos 1.600 subsidios y para 2023 lograr habilitar los 5 mil\u201d<\/strong>, indic\u00f3 Noguera.<\/p>\n<p>Asimismo, explic\u00f3 que los 6 millones 400 mil pesos del subsidio departamental (7 salarios m\u00ednimos) sumados a los 27 millones 400 mil de \u2018Mi Casa Ya\u2019 da un total de 33 millones 800 mil pesos, para que una familia pueda acceder a una vivienda VIP de 81 millones de pesos.<\/p>\n<p>Por su parte, la <strong>secretaria de Infraestructura, Nury Logreira<\/strong>, se\u00f1al\u00f3 que el subsidio \u2018Vivienda para la Gente\u2019 tiene dos prop\u00f3sitos: convertir en realidad el sue\u00f1o de la gente de tener su casa propia y reactivar la econom\u00eda, a trav\u00e9s del sector de la construcci\u00f3n. \u201cSiempre estamos pensando en la gente y en su bienestar. Y, a prop\u00f3sito de los 116 a\u00f1os del Atl\u00e1ntico, este es el mejor regalo que nuestra Gobernadora le puede dar al departamento\u201d, afirm\u00f3.<\/p>\n<p>La funcionaria agreg\u00f3 que todos los bancos con presencia en el departamento ya se encuentran habilitados para recibir a los potenciales clientes del programa, y que el proceso se inicia al escoger la vivienda e ir al banco de su preferencia. \u201cNo es necesario inscribirse en ninguna entidad p\u00fablica, caja de compensaci\u00f3n o terceros intermediarios. Es un proceso directo con los bancos y los constructores\u201d, aclar\u00f3 Logreira.<\/p>\n<p>El <strong>presidente de la Junta Directiva de Camacol Atl\u00e1ntico, Jorge Segebre,<\/strong> sostuvo que con el subsidio departamental m\u00e1s hogares tendr\u00e1n la oportunidad de acceder a vivienda en condiciones dignas. \u201cEn medio de la pandemia que estamos viviendo, los municipios del Atl\u00e1ntico necesitan m\u00e1s viviendas y que se reactive la econom\u00eda mediante la construcci\u00f3n de estas. Tambi\u00e9n representar\u00e1 una ventaja para nuestros j\u00f3venes que ganen un salario m\u00ednimo, quienes podr\u00e1n acceder a vivienda de inter\u00e9s prioritario nueva a bajas cuotas\u201d, resalt\u00f3.<\/p>\n<p>La inversi\u00f3n destinada por la Gobernaci\u00f3n del Atl\u00e1ntico para lograr habilitar los 5 mil subsidios adicionales es de 31 mil millones de pesos.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-6367 aligncenter\" src=\"https:\/\/contrastes.com.co\/digital\/wp-content\/uploads\/2021\/06\/subsidio-5-mil-2.jpg\" alt=\"subsidio 5 mil 2\" width=\"1200\" height=\"783\" \/><\/p>\n<h3><strong>\u00bfQui\u00e9nes pueden acceder al subsidio?<\/strong><\/h3>\n<p>Familias con ingresos de hasta 2 salarios m\u00ednimos, que deseen adquirir \u00fanicamente vivienda de inter\u00e9s prioritario y que cumplan con los requisitos del programa \u2018Mi Casa Ya\u2019 (consultar en la p\u00e1gina web <a href=\"http:\/\/www.micasaya.minvivienda.gov.co\"><strong>micasaya.minvivienda.gov.co<\/strong><\/a>).<\/p>\n<h3><strong>Los interesados deben seguir los siguientes pasos:<\/strong><\/h3>\n<p>1) Elegir el proyecto que sea de inter\u00e9s prioritario. El valor de la vivienda debe ser hasta 81.767.340 pesos (m\u00e1ximo 90 salarios a 2021).<\/p>\n<p>2) Luego, debe dirigirse a la entidad bancaria de su preferencia para iniciar el proceso.<\/p>\n<p>3) El banco proceder\u00e1 a habilitar y confirmar que el solicitante cumple con los requisitos.<\/p>\n<p>4) Una vez se confirme que cumple con los requisitos, el banco se encargar\u00e1 de tramitar ambos subsidios: el nacional y el departamental.<\/p>\n<h3><strong>\u00bfD\u00f3nde encontrar los proyectos?<\/strong><\/h3>\n<p>A trav\u00e9s de las vitrinas inmobiliarias como las que ofrece Camacol y los portales comerciales inmobiliarios en internet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el prop\u00f3sito de que m\u00e1s familias atlanticenses cumplan el sue\u00f1o de tener casa propia, la gobernadora del Atl\u00e1ntico, Elsa Noguera, present\u00f3 el subsidio adicional departamental \u2018Vivienda para la Gente\u2019, que beneficiar\u00e1 a 5 mil hogares y se suma al que entrega el Gobierno Nacional \u2018Mi Casa Ya\u2019.<\/p>\n","protected":false},"author":1,"featured_media":6366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2080,24,514],"tags":[77,15,3663,3664,908,3665,952,3666,3667],"class_list":["post-6365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bienestar","category-region","category-vivienda","tag-elsa-noguera","tag-gobernacion-del-atlantico","tag-jorge-segebre","tag-mi-casa-ya","tag-nury-logreira","tag-presidente-de-la-junta-directiva-de-camacol-atlantico","tag-secretaria-de-infraestructura","tag-subsidio-adicional-departamental-vivienda-para-la-gente","tag-vivienda-de-interes-prioritario-vip"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares - Constrastes<\/title>\n<meta name=\"description\" content=\"Con el prop\u00f3sito de que m\u00e1s familias atlanticenses cumplan el sue\u00f1o de tener casa propia, la gobernadora del Atl\u00e1ntico, Elsa Noguera, present\u00f3 el subsidio adicional departamental \u2018Vivienda para la Gente\u2019, que beneficiar\u00e1 a 5 mil hogares y se suma al que entrega el Gobierno Nacional \u2018Mi Casa Ya\u2019.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares - Constrastes\" \/>\n<meta property=\"og:description\" content=\"Con el prop\u00f3sito de que m\u00e1s familias atlanticenses cumplan el sue\u00f1o de tener casa propia, la gobernadora del Atl\u00e1ntico, Elsa Noguera, present\u00f3 el subsidio adicional departamental \u2018Vivienda para la Gente\u2019, que beneficiar\u00e1 a 5 mil hogares y se suma al que entrega el Gobierno Nacional \u2018Mi Casa Ya\u2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/\" \/>\n<meta property=\"og:site_name\" content=\"Constrastes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/guillo.pantoja.1\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-16T22:13:59+00:00\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\"},\"headline\":\"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares\",\"datePublished\":\"2021-06-16T22:13:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/\"},\"wordCount\":847,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"elsa noguera\",\"gobernaci\u00f3n del Atl\u00e1ntico\",\"Jorge Segebre\",\"Mi Casa Ya\",\"Nury Logreira\",\"presidente de la Junta Directiva de Camacol Atl\u00e1ntico\",\"secretaria de Infraestructura\",\"subsidio adicional departamental \u2018Vivienda para la Gente\",\"Vivienda de Inter\u00e9s Prioritario (VIP)\"],\"articleSection\":[\"Bienestar\",\"Regi\u00f3n\",\"Vivienda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/\",\"name\":\"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares - Constrastes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-06-16T22:13:59+00:00\",\"description\":\"Con el prop\u00f3sito de que m\u00e1s familias atlanticenses cumplan el sue\u00f1o de tener casa propia, la gobernadora del Atl\u00e1ntico, Elsa Noguera, present\u00f3 el subsidio adicional departamental \u2018Vivienda para la Gente\u2019, que beneficiar\u00e1 a 5 mil hogares y se suma al que entrega el Gobierno Nacional \u2018Mi Casa Ya\u2019.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/2021\\\/06\\\/16\\\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"name\":\"Contrastes\",\"description\":\"Periodismo de Conciencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\",\"name\":\"Contrastes\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"contentUrl\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"width\":1536,\"height\":231,\"caption\":\"Contrastes\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/guillo.pantoja.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/person\\\/62ef7a62dc4da6de450c71fc2e95ed02\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"sameAs\":[\"https:\\\/\\\/contrastes.com.co\\\/web\"],\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/author\\\/jdbobadilla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares - Constrastes","description":"Con el prop\u00f3sito de que m\u00e1s familias atlanticenses cumplan el sue\u00f1o de tener casa propia, la gobernadora del Atl\u00e1ntico, Elsa Noguera, present\u00f3 el subsidio adicional departamental \u2018Vivienda para la Gente\u2019, que beneficiar\u00e1 a 5 mil hogares y se suma al que entrega el Gobierno Nacional \u2018Mi Casa Ya\u2019.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/","og_locale":"es_ES","og_type":"article","og_title":"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares - Constrastes","og_description":"Con el prop\u00f3sito de que m\u00e1s familias atlanticenses cumplan el sue\u00f1o de tener casa propia, la gobernadora del Atl\u00e1ntico, Elsa Noguera, present\u00f3 el subsidio adicional departamental \u2018Vivienda para la Gente\u2019, que beneficiar\u00e1 a 5 mil hogares y se suma al que entrega el Gobierno Nacional \u2018Mi Casa Ya\u2019.","og_url":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/","og_site_name":"Constrastes","article_publisher":"https:\/\/www.facebook.com\/guillo.pantoja.1","article_published_time":"2021-06-16T22:13:59+00:00","author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/#article","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/"},"author":{"name":"Editor","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02"},"headline":"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares","datePublished":"2021-06-16T22:13:59+00:00","mainEntityOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/"},"wordCount":847,"commentCount":0,"publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/#primaryimage"},"thumbnailUrl":"","keywords":["elsa noguera","gobernaci\u00f3n del Atl\u00e1ntico","Jorge Segebre","Mi Casa Ya","Nury Logreira","presidente de la Junta Directiva de Camacol Atl\u00e1ntico","secretaria de Infraestructura","subsidio adicional departamental \u2018Vivienda para la Gente","Vivienda de Inter\u00e9s Prioritario (VIP)"],"articleSection":["Bienestar","Regi\u00f3n","Vivienda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/","url":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/","name":"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares - Constrastes","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/#primaryimage"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-06-16T22:13:59+00:00","description":"Con el prop\u00f3sito de que m\u00e1s familias atlanticenses cumplan el sue\u00f1o de tener casa propia, la gobernadora del Atl\u00e1ntico, Elsa Noguera, present\u00f3 el subsidio adicional departamental \u2018Vivienda para la Gente\u2019, que beneficiar\u00e1 a 5 mil hogares y se suma al que entrega el Gobierno Nacional \u2018Mi Casa Ya\u2019.","breadcrumb":{"@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/contrastes.com.co\/web\/2021\/06\/16\/vivienda-para-la-gente-subsidio-de-la-gobernacion-beneficiara-a-5-mil-hogares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contrastes.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"\u2018Vivienda para la Gente\u2019: Subsidio de la gobernaci\u00f3n beneficiar\u00e1 a 5 mil hogares"}]},{"@type":"WebSite","@id":"https:\/\/contrastes.com.co\/web\/#website","url":"https:\/\/contrastes.com.co\/web\/","name":"Contrastes","description":"Periodismo de Conciencia","publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contrastes.com.co\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contrastes.com.co\/web\/#organization","name":"Contrastes","url":"https:\/\/contrastes.com.co\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/","url":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","contentUrl":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","width":1536,"height":231,"caption":"Contrastes"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/guillo.pantoja.1"]},{"@type":"Person","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/person\/62ef7a62dc4da6de450c71fc2e95ed02","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7bbb4f718d74bbf600dc556253bb04fd7ac8593751d6e2e3b85432d98aefae80?s=96&d=mm&r=g","caption":"Editor"},"sameAs":["https:\/\/contrastes.com.co\/web"],"url":"https:\/\/contrastes.com.co\/web\/author\/jdbobadilla\/"}]}},"blog_post_layout_featured_media_urls":{"thumbnail":"","full":""},"categories_names":{"2080":{"name":"Bienestar","link":"https:\/\/contrastes.com.co\/web\/category\/bienestar\/"},"24":{"name":"Regi\u00f3n","link":"https:\/\/contrastes.com.co\/web\/category\/region\/"},"514":{"name":"Vivienda","link":"https:\/\/contrastes.com.co\/web\/category\/vivienda\/"}},"tags_names":{"77":{"name":"elsa noguera","link":"https:\/\/contrastes.com.co\/web\/tag\/elsa-noguera\/"},"15":{"name":"gobernaci\u00f3n del Atl\u00e1ntico","link":"https:\/\/contrastes.com.co\/web\/tag\/gobernacion-del-atlantico\/"},"3663":{"name":"Jorge Segebre","link":"https:\/\/contrastes.com.co\/web\/tag\/jorge-segebre\/"},"3664":{"name":"Mi Casa Ya","link":"https:\/\/contrastes.com.co\/web\/tag\/mi-casa-ya\/"},"908":{"name":"Nury Logreira","link":"https:\/\/contrastes.com.co\/web\/tag\/nury-logreira\/"},"3665":{"name":"presidente de la Junta Directiva de Camacol Atl\u00e1ntico","link":"https:\/\/contrastes.com.co\/web\/tag\/presidente-de-la-junta-directiva-de-camacol-atlantico\/"},"952":{"name":"secretaria de Infraestructura","link":"https:\/\/contrastes.com.co\/web\/tag\/secretaria-de-infraestructura\/"},"3666":{"name":"subsidio adicional departamental \u2018Vivienda para la Gente","link":"https:\/\/contrastes.com.co\/web\/tag\/subsidio-adicional-departamental-vivienda-para-la-gente\/"},"3667":{"name":"Vivienda de Inter\u00e9s Prioritario (VIP)","link":"https:\/\/contrastes.com.co\/web\/tag\/vivienda-de-interes-prioritario-vip\/"}},"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":"","cvmm-medium":"","cvmm-medium-plus":"","cvmm-portrait":"","cvmm-medium-square":"","cvmm-large":"","cvmm-small":"","full":""},"_links":{"self":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/6365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/comments?post=6365"}],"version-history":[{"count":0,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts\/6365\/revisions"}],"wp:attachment":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/media?parent=6365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/categories?post=6365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/tags?post=6365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}