{"id":9243,"count":1,"description":"","link":"https:\/\/contrastes.com.co\/web\/tag\/soneros-de-soledad\/","name":"Soneros de Soledad","slug":"soneros-de-soledad","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soneros de Soledad archivos - Constrastes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contrastes.com.co\/web\/tag\/soneros-de-soledad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soneros de Soledad archivos - Constrastes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contrastes.com.co\/web\/tag\/soneros-de-soledad\/\" \/>\n<meta property=\"og:site_name\" content=\"Constrastes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/tag\\\/soneros-de-soledad\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/tag\\\/soneros-de-soledad\\\/\",\"name\":\"Soneros de Soledad archivos - Constrastes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/tag\\\/soneros-de-soledad\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/tag\\\/soneros-de-soledad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soneros de Soledad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"name\":\"Contrastes\",\"description\":\"Periodismo de Conciencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#organization\",\"name\":\"Contrastes\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"contentUrl\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/15CONTRASTES3.png\",\"width\":1536,\"height\":231,\"caption\":\"Contrastes\"},\"image\":{\"@id\":\"https:\\\/\\\/contrastes.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/guillo.pantoja.1\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soneros de Soledad archivos - Constrastes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contrastes.com.co\/web\/tag\/soneros-de-soledad\/","og_locale":"es_ES","og_type":"article","og_title":"Soneros de Soledad archivos - Constrastes","og_url":"https:\/\/contrastes.com.co\/web\/tag\/soneros-de-soledad\/","og_site_name":"Constrastes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/contrastes.com.co\/web\/tag\/soneros-de-soledad\/","url":"https:\/\/contrastes.com.co\/web\/tag\/soneros-de-soledad\/","name":"Soneros de Soledad archivos - Constrastes","isPartOf":{"@id":"https:\/\/contrastes.com.co\/web\/#website"},"breadcrumb":{"@id":"https:\/\/contrastes.com.co\/web\/tag\/soneros-de-soledad\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/contrastes.com.co\/web\/tag\/soneros-de-soledad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contrastes.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"Soneros de Soledad"}]},{"@type":"WebSite","@id":"https:\/\/contrastes.com.co\/web\/#website","url":"https:\/\/contrastes.com.co\/web\/","name":"Contrastes","description":"Periodismo de Conciencia","publisher":{"@id":"https:\/\/contrastes.com.co\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contrastes.com.co\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contrastes.com.co\/web\/#organization","name":"Contrastes","url":"https:\/\/contrastes.com.co\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/","url":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","contentUrl":"https:\/\/contrastes.com.co\/web\/wp-content\/uploads\/2025\/04\/15CONTRASTES3.png","width":1536,"height":231,"caption":"Contrastes"},"image":{"@id":"https:\/\/contrastes.com.co\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/guillo.pantoja.1"]}]}},"_links":{"self":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/tags\/9243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/contrastes.com.co\/web\/wp-json\/wp\/v2\/posts?tags=9243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}